{"id":8333,"date":"2021-03-28T14:34:05","date_gmt":"2021-03-28T06:34:05","guid":{"rendered":"http:\/\/safeway-vise.com\/?post_type=product&#038;p=8333"},"modified":"2024-07-19T13:20:54","modified_gmt":"2024-07-19T05:20:54","slug":"mtl-100-400-a","status":"publish","type":"product","link":"https:\/\/safeway-vise.com\/en\/product\/mtl-100-400-a\/","title":{"rendered":"MTL-100-A"},"content":{"rendered":"<p class=\"text-center\"><mark>Block <strong>\"mtl-a\"<\/strong> not found<\/mark><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Flexible opening capacity for optimized application of different workpiece.<\/span><\/li>\n<li><span style=\"color: #000000;\"><span style=\"color: #339966;\"><span style=\"color: #000000;\">Most suitable for thick workpiece, special design for increasing stability of clamping capacity. <\/span><\/span><\/span><\/li>\n<li><span style=\"color: #000000;\">High clamping forces, suitable for heavy duty working<\/span><\/li>\n<li><span style=\"color: #000000;\">Vise body- sliding surface: Hardened <sup>,<\/sup>Durable and Accurate.<\/span><\/li>\n<li><span style=\"color: #000000;\">Easy for add-on components for increasing working efficiency<\/span><\/li>\n<li><span style=\"color: #000000;\">Model: MTL-A (Single-2 piece) \/ MTL-D (Single-3 piece) \/ MTL-T (Twin-piece)<\/span><\/li>\n<li><span style=\"color: #000000;\">Full ranges from jaw width (50 \/ 72 \/ 100) x length (300 \/ 400 \/ 500 \/ 600 \/ 700)<\/span><\/li>\n<li>Specifications:<\/li>\n<\/ul>\n<p style=\"text-align: center;\">\n<div class=\"wpdt-c row wpDataTableContainerSimpleTable wpDataTables wpDataTablesWrapper\n wdtscroll\"\n    >\n        <table id=\"wpdtSimpleTable-71\"\n           style=\"border-collapse:collapse;\n                   border-spacing:0px;\"\n           class=\"wpdtSimpleTable wpDataTable\"\n           data-column=\"17\"\n           data-rows=\"5\"\n           data-wpID=\"71\"\n           data-responsive=\"0\"\n           data-has-header=\"1\">\n\n                    <thead>        <tr class=\"wpdt-cell-row \" >\n                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"A1\"\n                    data-col-index=\"0\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        No.                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016 wpdt-overflow-text\"\n                                            data-cell-id=\"B1\"\n                    data-col-index=\"1\"\n                    data-row-index=\"0\"\n                    style=\" width:160px;                    padding:10px;\n                    \"\n                    >\n                                        Model                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"C1\"\n                    data-col-index=\"2\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        A                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"D1\"\n                    data-col-index=\"3\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        B                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"E1\"\n                    data-col-index=\"4\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        E                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"F1\"\n                    data-col-index=\"5\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        F                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"G1\"\n                    data-col-index=\"6\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        H                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"H1\"\n                    data-col-index=\"7\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        J                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"I1\"\n                    data-col-index=\"8\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        K                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"J1\"\n                    data-col-index=\"9\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        L                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"K1\"\n                    data-col-index=\"10\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        M                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"L1\"\n                    data-col-index=\"11\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        N                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"M1\"\n                    data-col-index=\"12\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        P                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"N1\"\n                    data-col-index=\"13\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        R                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"O1\"\n                    data-col-index=\"14\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        S                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"P1\"\n                    data-col-index=\"15\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        W                    <\/th>\n                                                <th class=\"wpdt-cell wpdt-bold wpdt-fs-000016\"\n                                            data-cell-id=\"Q1\"\n                    data-col-index=\"16\"\n                    data-row-index=\"0\"\n                    style=\" width:100px;                    padding:10px;\n                    \"\n                    >\n                                        N.W.                    <\/th>\n                                        <\/tr>\n                    <tbody>        <tr class=\"wpdt-cell-row odd\" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A2\"\n                    data-col-index=\"0\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        43410040                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-overflow-text\"\n                                            data-cell-id=\"B2\"\n                    data-col-index=\"1\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        MTL-100-400-A                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C2\"\n                    data-col-index=\"2\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        400                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"D2\"\n                    data-col-index=\"3\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        100                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"E2\"\n                    data-col-index=\"4\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"F2\"\n                    data-col-index=\"5\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        45                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"G2\"\n                    data-col-index=\"6\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        115                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"H2\"\n                    data-col-index=\"7\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        75                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"I2\"\n                    data-col-index=\"8\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"J2\"\n                    data-col-index=\"9\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"K2\"\n                    data-col-index=\"10\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        16                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"L2\"\n                    data-col-index=\"11\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"M2\"\n                    data-col-index=\"12\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        200                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"N2\"\n                    data-col-index=\"13\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"O2\"\n                    data-col-index=\"14\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        M16x50Lx4                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"P2\"\n                    data-col-index=\"15\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        4x7                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"Q2\"\n                    data-col-index=\"16\"\n                    data-row-index=\"1\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        30.0                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row even\" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A3\"\n                    data-col-index=\"0\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        43410050                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-overflow-text\"\n                                            data-cell-id=\"B3\"\n                    data-col-index=\"1\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        MTL-100-500-A                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C3\"\n                    data-col-index=\"2\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        500                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"D3\"\n                    data-col-index=\"3\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        100                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"E3\"\n                    data-col-index=\"4\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"F3\"\n                    data-col-index=\"5\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        45                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"G3\"\n                    data-col-index=\"6\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        115                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"H3\"\n                    data-col-index=\"7\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        75                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"I3\"\n                    data-col-index=\"8\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"J3\"\n                    data-col-index=\"9\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"K3\"\n                    data-col-index=\"10\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        16                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"L3\"\n                    data-col-index=\"11\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"M3\"\n                    data-col-index=\"12\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        300                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"N3\"\n                    data-col-index=\"13\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"O3\"\n                    data-col-index=\"14\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        M16x50Lx5                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"P3\"\n                    data-col-index=\"15\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        4x32                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"Q3\"\n                    data-col-index=\"16\"\n                    data-row-index=\"2\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        34.0                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row odd\" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A4\"\n                    data-col-index=\"0\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        43410060                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-overflow-text\"\n                                            data-cell-id=\"B4\"\n                    data-col-index=\"1\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        MTL-100-600-A                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C4\"\n                    data-col-index=\"2\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        600                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"D4\"\n                    data-col-index=\"3\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        100                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"E4\"\n                    data-col-index=\"4\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"F4\"\n                    data-col-index=\"5\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        45                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"G4\"\n                    data-col-index=\"6\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        115                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"H4\"\n                    data-col-index=\"7\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        75                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"I4\"\n                    data-col-index=\"8\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"J4\"\n                    data-col-index=\"9\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"K4\"\n                    data-col-index=\"10\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        16                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"L4\"\n                    data-col-index=\"11\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"M4\"\n                    data-col-index=\"12\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        400                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"N4\"\n                    data-col-index=\"13\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"O4\"\n                    data-col-index=\"14\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        M16x50Lx6                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"P4\"\n                    data-col-index=\"15\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        4x57                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"Q4\"\n                    data-col-index=\"16\"\n                    data-row-index=\"3\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        38.4                    <\/td>\n                                        <\/tr>\n                            <tr class=\"wpdt-cell-row even\" >\n                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"A5\"\n                    data-col-index=\"0\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        43410070                    <\/td>\n                                                <td class=\"wpdt-cell wpdt-overflow-text\"\n                                            data-cell-id=\"B5\"\n                    data-col-index=\"1\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        MTL-100-700-A                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"C5\"\n                    data-col-index=\"2\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        700                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"D5\"\n                    data-col-index=\"3\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        100                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"E5\"\n                    data-col-index=\"4\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"F5\"\n                    data-col-index=\"5\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        45                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"G5\"\n                    data-col-index=\"6\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        115                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"H5\"\n                    data-col-index=\"7\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        75                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"I5\"\n                    data-col-index=\"8\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        70                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"J5\"\n                    data-col-index=\"9\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        14                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"K5\"\n                    data-col-index=\"10\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        16                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"L5\"\n                    data-col-index=\"11\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"M5\"\n                    data-col-index=\"12\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        500                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"N5\"\n                    data-col-index=\"13\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        18                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"O5\"\n                    data-col-index=\"14\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        M16x50Lx7                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"P5\"\n                    data-col-index=\"15\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        4x85                    <\/td>\n                                                <td class=\"wpdt-cell \"\n                                            data-cell-id=\"Q5\"\n                    data-col-index=\"16\"\n                    data-row-index=\"4\"\n                    style=\"                    padding:10px;\n                    \"\n                    >\n                                        42.5                    <\/td>\n                                        <\/tr>\n                    <\/table>\n<\/div><style id='wpdt-custom-style-71'>\n.wpdt-fs-000016 { font-size: 16px !important;}\n<\/style>\n<style>\n        \/* table font color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable thead th,\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable tbody td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tbody td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tfoot td {\n        color: #3F3F3F !important;\n    }\n\n                    \/* th font color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable.bt[data-has-header='1'] td.wpdt-header-classes,\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable thead th,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th {\n        color: #3F3F3F !important;\n    }\n\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting:after,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting_asc:after {\n        border-bottom-color: #3F3F3F !important;\n    }\n\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting_desc:after {\n        border-top-color: #3F3F3F !important;\n    }\n\n            \/* th active\/hover background color *\/\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting_asc,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting_desc,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable thead th.sorting:hover,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable.wpdtSimpleTable thead th:hover,\n    .wpdt-c.wpDataTablesWrapper table.wpDataTable.wpdtSimpleTable thead th:hover {\n        background-color: #939393 !important;\n        background-image: none !important;\n    }\n\n    \n                \/* odd rows background color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable tr.odd td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.odd td {\n        background-color: #FFFFFF !important;\n    }\n\n            \/* even rows background color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable tr.even td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.even td,\n    .wpdt-c .wpDataTablesWrapper table.has-columns-hidden tr.row-detail > td {\n        background-color: #FFFFFF !important;\n    }\n\n                    \/* rows hover background color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable tr.odd:hover > td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.odd:hover > td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.odd:hover > td.sorting_1,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.even:hover > td,\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable tr.even:hover > td,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable tr.even:hover > td.sorting_1 {\n        background-color: #EFEFEF !important;\n    }\n\n                                                                \/* table font color *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable {\n        font-family: Arial, Helvetica, sans-serif !important;\n    }\n\n            \/* table font size *\/\n    .wpdt-c.wpDataTablesWrapper table.wpdtSimpleTable,\n    .wpdt-c .wpDataTablesWrapper table.wpDataTable {\n        font-size: 16px !important;\n    }\n\n            \n            \/* pagination other pages hover color *\/\n    .wpDataTablesWrapper .dataTables_paginate .paginate_button:hover:not(.disabled):not(.current),\n    .wpDataTablesWrapper .paginate_button.previous:hover:before,\n    .wpDataTablesWrapper .paginate_button.first:hover:before,\n    .wpDataTablesWrapper .paginate_button.next:hover:before,\n    .wpDataTablesWrapper .paginate_button.last:hover:before {\n        color: #3F51B5 !important;\n    }\n\n            <\/style>\n\n","protected":false},"excerpt":{"rendered":"<h3 style=\"text-align: left;\">Multiple Clamping System (Single- 2 pieces)<\/h3>\n<a href=\"https:\/\/safeway-vise.com\/wp-content\/uploads\/MTL-A.pdf\" target=\"_blank\" class=\"button primary is-outline\" rel=\"noopener\" >\n\t\t<span>Catalogue<\/span>\n\t<\/a>\n\n","protected":false},"featured_media":5056,"template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[966],"class_list":{"0":"post-8333","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessories","7":"product_tag-multiple-clamping-vise-en","9":"first","10":"instock","11":"featured","12":"shipping-taxable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/product\/8333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/media\/5056"}],"wp:attachment":[{"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/media?parent=8333"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/product_brand?post=8333"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/product_cat?post=8333"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/safeway-vise.com\/en\/wp-json\/wp\/v2\/product_tag?post=8333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}